{"id":253,"count":5,"description":"<p style=\"text-align: center;\">La pr\u00e9paration d'un voyage n'est pas toujours une partie de plaisir, on doit penser \u00e0 tout ! Alors pour ne rien oublier voici une s\u00e9rie d'article \u00e0 lire avant de partir.<\/p>\r\n&nbsp;\r\n\r\n<hr \/>\r\n\r\n&nbsp;","link":"https:\/\/www.desfenetressurlemonde.com\/en\/cat\/avant-de-partir\/","name":"Before leaving","slug":"avant-de-partir","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avant de partir - Des Fen\u00eatres sur le Monde<\/title>\n<meta name=\"description\" content=\"La pr\u00e9paration d&rsquo;un voyage n&rsquo;est pas toujours une partie de plaisir, on doit penser \u00e0 tout ! Alors pour ne rien oublier voici une s\u00e9rie d&rsquo;article \u00e0 lire avant de partir. &nbsp; &nbsp;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.desfenetressurlemonde.com\/en\/cat\/avant-de-partir\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avant de partir - Des Fen\u00eatres sur le Monde\" \/>\n<meta property=\"og:description\" content=\"La pr\u00e9paration d&rsquo;un voyage n&rsquo;est pas toujours une partie de plaisir, on doit penser \u00e0 tout ! Alors pour ne rien oublier voici une s\u00e9rie d&rsquo;article \u00e0 lire avant de partir. &nbsp; &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.desfenetressurlemonde.com\/en\/cat\/avant-de-partir\/\" \/>\n<meta property=\"og:site_name\" content=\"Des Fen\u00eatres sur le Monde\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.desfenetressurlemonde.com\\\/en\\\/cat\\\/avant-de-partir\\\/\",\"url\":\"https:\\\/\\\/www.desfenetressurlemonde.com\\\/en\\\/cat\\\/avant-de-partir\\\/\",\"name\":\"Avant de partir - Des Fen\u00eatres sur le Monde\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.desfenetressurlemonde.com\\\/#website\"},\"description\":\"La pr\u00e9paration d&rsquo;un voyage n&rsquo;est pas toujours une partie de plaisir, on doit penser \u00e0 tout ! Alors pour ne rien oublier voici une s\u00e9rie d&rsquo;article \u00e0 lire avant de partir. &nbsp; &nbsp;\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.desfenetressurlemonde.com\\\/en\\\/cat\\\/avant-de-partir\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.desfenetressurlemonde.com\\\/en\\\/cat\\\/avant-de-partir\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.desfenetressurlemonde.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avant de partir\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.desfenetressurlemonde.com\\\/#website\",\"url\":\"http:\\\/\\\/www.desfenetressurlemonde.com\\\/\",\"name\":\"Des Fen\u00eatres sur le Monde\",\"description\":\"Joana &amp; Eric en vadrouille...\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.desfenetressurlemonde.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avant de partir - Des Fen\u00eatres sur le Monde","description":"Preparing for a trip is not always a pleasure, we have to think of everything! So to remember nothing here is a series of articles to read before leaving. &nbsp; &nbsp;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.desfenetressurlemonde.com\/en\/cat\/avant-de-partir\/","og_locale":"en_GB","og_type":"article","og_title":"Avant de partir - Des Fen\u00eatres sur le Monde","og_description":"La pr\u00e9paration d&rsquo;un voyage n&rsquo;est pas toujours une partie de plaisir, on doit penser \u00e0 tout ! Alors pour ne rien oublier voici une s\u00e9rie d&rsquo;article \u00e0 lire avant de partir. &nbsp; &nbsp;","og_url":"https:\/\/www.desfenetressurlemonde.com\/en\/cat\/avant-de-partir\/","og_site_name":"Des Fen\u00eatres sur le Monde","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.desfenetressurlemonde.com\/en\/cat\/avant-de-partir\/","url":"https:\/\/www.desfenetressurlemonde.com\/en\/cat\/avant-de-partir\/","name":"Avant de partir - Des Fen\u00eatres sur le Monde","isPartOf":{"@id":"http:\/\/www.desfenetressurlemonde.com\/#website"},"description":"Preparing for a trip is not always a pleasure, we have to think of everything! So to remember nothing here is a series of articles to read before leaving. &nbsp; &nbsp;","breadcrumb":{"@id":"https:\/\/www.desfenetressurlemonde.com\/en\/cat\/avant-de-partir\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/www.desfenetressurlemonde.com\/en\/cat\/avant-de-partir\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.desfenetressurlemonde.com\/"},{"@type":"ListItem","position":2,"name":"Avant de partir"}]},{"@type":"WebSite","@id":"http:\/\/www.desfenetressurlemonde.com\/#website","url":"http:\/\/www.desfenetressurlemonde.com\/","name":"Windows on the World","description":"Joana &amp; Eric en vadrouille...","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.desfenetressurlemonde.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/www.desfenetressurlemonde.com\/en\/wp-json\/wp\/v2\/categories\/253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.desfenetressurlemonde.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.desfenetressurlemonde.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.desfenetressurlemonde.com\/en\/wp-json\/wp\/v2\/posts?categories=253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}